{"id":43,"date":"2026-05-13T10:48:02","date_gmt":"2026-05-13T10:48:02","guid":{"rendered":"https:\/\/valmoreira.com\/index.php\/2026\/05\/13\/harmonizacao-vinho-verde-e-gastronomia\/"},"modified":"2026-05-13T10:48:02","modified_gmt":"2026-05-13T10:48:02","slug":"harmonizacao-vinho-verde-e-gastronomia","status":"publish","type":"post","link":"https:\/\/valmoreira.com\/index.php\/2026\/05\/13\/harmonizacao-vinho-verde-e-gastronomia\/","title":{"rendered":"Harmoniza\u00e7\u00e3o: Vinho Verde e Gastronomia"},"content":{"rendered":"<p>Aprenda a combinar o nosso Vinho Verde Escolha com os melhores pratos da gastronomia portuguesa e internacional. Dicas dos nossos en\u00f3logos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprenda a combinar o nosso Vinho Verde Escolha com os melhores pratos da gastronomia portuguesa e internacional. Dicas dos nossos&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-43","post","type-post","status-publish","format-standard","hentry","category-gastronomia"],"_links":{"self":[{"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/posts\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":0,"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/posts\/43\/revisions"}],"wp:attachment":[{"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/media?parent=43"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/categories?post=43"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valmoreira.com\/index.php\/wp-json\/wp\/v2\/tags?post=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}